{"id":271,"date":"2012-12-18T16:34:19","date_gmt":"2012-12-18T15:34:19","guid":{"rendered":"https:\/\/www.journal.topaze.com\/?p=271"},"modified":"2019-06-05T16:53:02","modified_gmt":"2019-06-05T14:53:02","slug":"comment-imprimer-un-double-de-facture","status":"publish","type":"post","link":"https:\/\/www.journal.topaze.com\/orthophoniste\/blog\/2012\/12\/18\/comment-imprimer-un-double-de-facture\/","title":{"rendered":"Comment imprimer un double de facture ?"},"content":{"rendered":"<p><span style=\"text-decoration: underline;\"><strong>M\u00e9thode 1 :<\/strong><\/span><\/p>\n<p><strong>Acc\u00e8s :<\/strong> Univers Factures &amp; t\u00e9l\u00e9trans &gt; onglet \u00ab\u00a0A transmettre\u00a0\u00bb ou \u00ab\u00a0Suivi factures\u00a0\u00bb :\u00a0dans \u00ab\u00a0Afficher les factures\u00a0\u00bb, s\u00e9lectionnez \u00ab\u00a0Toutes\u00a0\u00bb<\/p>\n<ol>\n<li>S\u00e9lectionnez la ligne de la facture d\u00e9sir\u00e9e<\/li>\n<li>Cliquez sur le bouton \u00ab\u00a0Dble facture\u00a0\u00bb<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-275\" alt=\"DBL_Facture\" src=\"https:\/\/www.journal.topaze.com\/wp-content\/uploads\/sites\/12\/2012\/12\/DBL_Facture.jpg\" width=\"61\" height=\"57\" \/><\/li>\n<\/ol>\n<p><span style=\"text-decoration: underline;\"><strong>M\u00e9thode 2 :<\/strong><\/span><\/p>\n<p><strong>Acc\u00e8s :<\/strong> Univers Patients &amp; traitements &gt; onglet \u00ab\u00a0Dossier m\u00e9dical\u00a0\u00bb<\/p>\n<ol>\n<li>Double cliquez sur la facture d\u00e9sir\u00e9e<\/li>\n<li>Cliquez sur le bouton \u00ab\u00a0Imprimer\u00a0\u00bb de la feuille de soins<\/li>\n<\/ol>\n<p><strong>Remarque :<\/strong> Il est possible de faire apparaitre ou disparaitre la mention \u00ab\u00a0Duplicata\u00a0\u00bb en cochant ou d\u00e9cochant cette option sur le masque de la feuille de soins<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-274\" alt=\"Duplicata\" src=\"https:\/\/www.journal.topaze.com\/wp-content\/uploads\/sites\/12\/2012\/12\/Duplicata.jpg\" width=\"170\" height=\"40\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9thode 1 : Acc\u00e8s : Univers Factures &amp; t\u00e9l\u00e9trans &gt; onglet \u00ab\u00a0A transmettre\u00a0\u00bb ou \u00ab\u00a0Suivi factures\u00a0\u00bb :\u00a0dans \u00ab\u00a0Afficher les factures\u00a0\u00bb, s\u00e9lectionnez \u00ab\u00a0Toutes\u00a0\u00bb S\u00e9lectionnez la ligne de la facture d\u00e9sir\u00e9e Cliquez sur le bouton \u00ab\u00a0Dble facture\u00a0\u00bb M\u00e9thode 2 : Acc\u00e8s : Univers Patients &amp; traitements &gt; onglet \u00ab\u00a0Dossier m\u00e9dical\u00a0\u00bb Double cliquez sur la facture d\u00e9sir\u00e9e Cliquez [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[474],"tags":[6,7,9,11,137,3,4],"class_list":["post-271","post","type-post","status-publish","format-standard","hentry","category-fiches-formations","tag-orthoptiste","tag-orthophoniste","tag-infirmier","tag-sage-femme","tag-facture","tag-kinesitherapeute","tag-toutes-professions-paramedicales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comment imprimer un double de facture ? - Orthophoniste<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment imprimer un double de facture ? - Orthophoniste\" \/>\n<meta property=\"og:description\" content=\"M\u00e9thode 1 : Acc\u00e8s : Univers Factures &amp; t\u00e9l\u00e9trans &gt; onglet \u00ab\u00a0A transmettre\u00a0\u00bb ou \u00ab\u00a0Suivi factures\u00a0\u00bb :\u00a0dans \u00ab\u00a0Afficher les factures\u00a0\u00bb, s\u00e9lectionnez \u00ab\u00a0Toutes\u00a0\u00bb S\u00e9lectionnez la ligne de la facture d\u00e9sir\u00e9e Cliquez sur le bouton \u00ab\u00a0Dble facture\u00a0\u00bb M\u00e9thode 2 : Acc\u00e8s : Univers Patients &amp; traitements &gt; onglet \u00ab\u00a0Dossier m\u00e9dical\u00a0\u00bb Double cliquez sur la facture d\u00e9sir\u00e9e Cliquez [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.journal.topaze.com\/orthophoniste\/blog\/2012\/12\/18\/comment-imprimer-un-double-de-facture\/\" \/>\n<meta property=\"og:site_name\" content=\"Orthophoniste\" \/>\n<meta property=\"article:published_time\" content=\"2012-12-18T15:34:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-05T14:53:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.journal.topaze.com\/wp-content\/uploads\/sites\/12\/2012\/12\/DBL_Facture.jpg\" \/>\n<meta name=\"author\" content=\"Laurence SANCHIS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laurence SANCHIS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.journal.topaze.com\/orthophoniste\/blog\/2012\/12\/18\/comment-imprimer-un-double-de-facture\/\",\"url\":\"https:\/\/www.journal.topaze.com\/orthophoniste\/blog\/2012\/12\/18\/comment-imprimer-un-double-de-facture\/\",\"name\":\"Comment imprimer un double de facture ? - Orthophoniste\",\"isPartOf\":{\"@id\":\"https:\/\/www.journal.topaze.com\/orthophoniste\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.journal.topaze.com\/orthophoniste\/blog\/2012\/12\/18\/comment-imprimer-un-double-de-facture\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.journal.topaze.com\/orthophoniste\/blog\/2012\/12\/18\/comment-imprimer-un-double-de-facture\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.journal.topaze.com\/wp-content\/uploads\/sites\/12\/2012\/12\/DBL_Facture.jpg\",\"datePublished\":\"2012-12-18T15:34:19+00:00\",\"dateModified\":\"2019-06-05T14:53:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.journal.topaze.com\/orthophoniste\/#\/schema\/person\/c766284c1b673ed4812f97e9564294e4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.journal.topaze.com\/orthophoniste\/blog\/2012\/12\/18\/comment-imprimer-un-double-de-facture\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.journal.topaze.com\/orthophoniste\/blog\/2012\/12\/18\/comment-imprimer-un-double-de-facture\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.journal.topaze.com\/orthophoniste\/blog\/2012\/12\/18\/comment-imprimer-un-double-de-facture\/#primaryimage\",\"url\":\"https:\/\/www.journal.topaze.com\/wp-content\/uploads\/sites\/12\/2012\/12\/DBL_Facture.jpg\",\"contentUrl\":\"https:\/\/www.journal.topaze.com\/wp-content\/uploads\/sites\/12\/2012\/12\/DBL_Facture.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.journal.topaze.com\/orthophoniste\/blog\/2012\/12\/18\/comment-imprimer-un-double-de-facture\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.journal.topaze.com\/orthophoniste\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment imprimer un double de facture ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.journal.topaze.com\/orthophoniste\/#website\",\"url\":\"https:\/\/www.journal.topaze.com\/orthophoniste\/\",\"name\":\"Orthophoniste\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.journal.topaze.com\/orthophoniste\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.journal.topaze.com\/orthophoniste\/#\/schema\/person\/c766284c1b673ed4812f97e9564294e4\",\"name\":\"Laurence SANCHIS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.journal.topaze.com\/orthophoniste\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1082eb661868f47801b96929dc132c79?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1082eb661868f47801b96929dc132c79?s=96&d=mm&r=g\",\"caption\":\"Laurence SANCHIS\"},\"url\":\"https:\/\/www.journal.topaze.com\/orthophoniste\/blog\/author\/laurence-sanchis\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment imprimer un double de facture ? - Orthophoniste","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Comment imprimer un double de facture ? - Orthophoniste","og_description":"M\u00e9thode 1 : Acc\u00e8s : Univers Factures &amp; t\u00e9l\u00e9trans &gt; onglet \u00ab\u00a0A transmettre\u00a0\u00bb ou \u00ab\u00a0Suivi factures\u00a0\u00bb :\u00a0dans \u00ab\u00a0Afficher les factures\u00a0\u00bb, s\u00e9lectionnez \u00ab\u00a0Toutes\u00a0\u00bb S\u00e9lectionnez la ligne de la facture d\u00e9sir\u00e9e Cliquez sur le bouton \u00ab\u00a0Dble facture\u00a0\u00bb M\u00e9thode 2 : Acc\u00e8s : Univers Patients &amp; traitements &gt; onglet \u00ab\u00a0Dossier m\u00e9dical\u00a0\u00bb Double cliquez sur la facture d\u00e9sir\u00e9e Cliquez [&hellip;]","og_url":"https:\/\/www.journal.topaze.com\/orthophoniste\/blog\/2012\/12\/18\/comment-imprimer-un-double-de-facture\/","og_site_name":"Orthophoniste","article_published_time":"2012-12-18T15:34:19+00:00","article_modified_time":"2019-06-05T14:53:02+00:00","og_image":[{"url":"https:\/\/www.journal.topaze.com\/wp-content\/uploads\/sites\/12\/2012\/12\/DBL_Facture.jpg","type":"","width":"","height":""}],"author":"Laurence SANCHIS","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Laurence SANCHIS","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.journal.topaze.com\/orthophoniste\/blog\/2012\/12\/18\/comment-imprimer-un-double-de-facture\/","url":"https:\/\/www.journal.topaze.com\/orthophoniste\/blog\/2012\/12\/18\/comment-imprimer-un-double-de-facture\/","name":"Comment imprimer un double de facture ? - Orthophoniste","isPartOf":{"@id":"https:\/\/www.journal.topaze.com\/orthophoniste\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.journal.topaze.com\/orthophoniste\/blog\/2012\/12\/18\/comment-imprimer-un-double-de-facture\/#primaryimage"},"image":{"@id":"https:\/\/www.journal.topaze.com\/orthophoniste\/blog\/2012\/12\/18\/comment-imprimer-un-double-de-facture\/#primaryimage"},"thumbnailUrl":"https:\/\/www.journal.topaze.com\/wp-content\/uploads\/sites\/12\/2012\/12\/DBL_Facture.jpg","datePublished":"2012-12-18T15:34:19+00:00","dateModified":"2019-06-05T14:53:02+00:00","author":{"@id":"https:\/\/www.journal.topaze.com\/orthophoniste\/#\/schema\/person\/c766284c1b673ed4812f97e9564294e4"},"breadcrumb":{"@id":"https:\/\/www.journal.topaze.com\/orthophoniste\/blog\/2012\/12\/18\/comment-imprimer-un-double-de-facture\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.journal.topaze.com\/orthophoniste\/blog\/2012\/12\/18\/comment-imprimer-un-double-de-facture\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.journal.topaze.com\/orthophoniste\/blog\/2012\/12\/18\/comment-imprimer-un-double-de-facture\/#primaryimage","url":"https:\/\/www.journal.topaze.com\/wp-content\/uploads\/sites\/12\/2012\/12\/DBL_Facture.jpg","contentUrl":"https:\/\/www.journal.topaze.com\/wp-content\/uploads\/sites\/12\/2012\/12\/DBL_Facture.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.journal.topaze.com\/orthophoniste\/blog\/2012\/12\/18\/comment-imprimer-un-double-de-facture\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.journal.topaze.com\/orthophoniste\/"},{"@type":"ListItem","position":2,"name":"Comment imprimer un double de facture ?"}]},{"@type":"WebSite","@id":"https:\/\/www.journal.topaze.com\/orthophoniste\/#website","url":"https:\/\/www.journal.topaze.com\/orthophoniste\/","name":"Orthophoniste","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.journal.topaze.com\/orthophoniste\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.journal.topaze.com\/orthophoniste\/#\/schema\/person\/c766284c1b673ed4812f97e9564294e4","name":"Laurence SANCHIS","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.journal.topaze.com\/orthophoniste\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1082eb661868f47801b96929dc132c79?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1082eb661868f47801b96929dc132c79?s=96&d=mm&r=g","caption":"Laurence SANCHIS"},"url":"https:\/\/www.journal.topaze.com\/orthophoniste\/blog\/author\/laurence-sanchis\/"}]}},"_links":{"self":[{"href":"https:\/\/www.journal.topaze.com\/orthophoniste\/wp-json\/wp\/v2\/posts\/271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.journal.topaze.com\/orthophoniste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.journal.topaze.com\/orthophoniste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.journal.topaze.com\/orthophoniste\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.journal.topaze.com\/orthophoniste\/wp-json\/wp\/v2\/comments?post=271"}],"version-history":[{"count":1,"href":"https:\/\/www.journal.topaze.com\/orthophoniste\/wp-json\/wp\/v2\/posts\/271\/revisions"}],"predecessor-version":[{"id":10186,"href":"https:\/\/www.journal.topaze.com\/orthophoniste\/wp-json\/wp\/v2\/posts\/271\/revisions\/10186"}],"wp:attachment":[{"href":"https:\/\/www.journal.topaze.com\/orthophoniste\/wp-json\/wp\/v2\/media?parent=271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.journal.topaze.com\/orthophoniste\/wp-json\/wp\/v2\/categories?post=271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.journal.topaze.com\/orthophoniste\/wp-json\/wp\/v2\/tags?post=271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}